{"id":6880,"date":"2017-02-21T13:17:45","date_gmt":"2017-02-21T13:17:45","guid":{"rendered":"http:\/\/spsc.pt\/?p=6880"},"modified":"2017-02-21T13:17:45","modified_gmt":"2017-02-21T13:17:45","slug":"procriacao-medicamente-assistida-e-gestacao-de-substituicao-em-coloquio-em-coimbra","status":"publish","type":"post","link":"https:\/\/spsc.pt\/index.php\/2017\/02\/21\/procriacao-medicamente-assistida-e-gestacao-de-substituicao-em-coloquio-em-coimbra\/","title":{"rendered":"Procria\u00e7\u00e3o Medicamente Assistida e Gesta\u00e7\u00e3o de Substitui\u00e7\u00e3o em Col\u00f3quio em Coimbra"},"content":{"rendered":"<p>A <em>Procria\u00e7\u00e3o Medicamente Assistida<\/em> e a <em>Gesta\u00e7\u00e3o de Substitui\u00e7\u00e3o<\/em> ser\u00e3o os temas centrais do Col\u00f3quio Internacional \u201cQueering Parenting\u201d, que re\u00fane em Coimbra, entre 2 e 3 de mar\u00e7o, 150 delegados\/as de todo o mundo. O evento \u2013 que tem lugar no Teatro da Cerca de S\u00e3o Bernardo e no Centro de Estudos Sociais (CES) \u2013 \u00e9 uma iniciativa do projeto <em>Intimate: Cidadania, Cuidado e Escolha \u2013 A Micropol\u00edtica da Intimidade na Europa do Sul<\/em>, coordenado por Ana Cristina Santos e financiado pelo Conselho Europeu de Investiga\u00e7\u00e3o (ERC).<\/p>\n<p>No encontro apresentam-se os principais resultados dos estudos implementados em Portugal, Espanha e It\u00e1lia, em torno do tema das parentalidades LGBT\/Queer, com especial aten\u00e7\u00e3o aos t\u00f3picos da <em>Procria\u00e7\u00e3o Medicamente Assistida<\/em> e da <em>Gesta\u00e7\u00e3o de Substitui\u00e7\u00e3o<\/em>.<\/p>\n<p>Mais informa\u00e7\u00f5es <a href=\"http:\/\/www.ces.uc.pt\/intimate\/index.php?id=10437&amp;id_lingua=2&amp;pag=10452\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Procria\u00e7\u00e3o Medicamente Assistida e a Gesta\u00e7\u00e3o de Substitui\u00e7\u00e3o ser\u00e3o os temas centrais do Col\u00f3quio Internacional \u201cQueering Parenting\u201d, que re\u00fane em Coimbra, entre 2 e 3 de mar\u00e7o, 150 delegados\/as de todo o mundo. O evento \u2013 que tem lugar no Teatro da Cerca de S\u00e3o Bernardo e no Centro de Estudos Sociais (CES) \u2013 [&hellip;]<\/p>\n","protected":false},"author":500,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60,36],"tags":[287,286,285,283,284,242],"class_list":["post-6880","post","type-post","status-publish","format-standard","hentry","category-eventos-cientificos-nacionais","category-noticias","tag-coloquio-queering-parenting","tag-conselho-europeu-de-investigacao","tag-cuidado-e-escolha-a-micropolitica-da-intimidade-na-europa-do-sul","tag-gestacao-de-substituicao","tag-ntimate-cidadania","tag-procriacao-medicamente-assistida"],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts\/6880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/users\/500"}],"replies":[{"embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/comments?post=6880"}],"version-history":[{"count":2,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts\/6880\/revisions"}],"predecessor-version":[{"id":6884,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts\/6880\/revisions\/6884"}],"wp:attachment":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/media?parent=6880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/categories?post=6880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/tags?post=6880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}