{"id":6967,"date":"2017-03-20T08:52:35","date_gmt":"2017-03-20T08:52:35","guid":{"rendered":"http:\/\/spsc.pt\/?p=6967"},"modified":"2017-03-20T08:56:10","modified_gmt":"2017-03-20T08:56:10","slug":"congresso-internacional-sobre-intersexualidades-no-porto","status":"publish","type":"post","link":"https:\/\/spsc.pt\/index.php\/2017\/03\/20\/congresso-internacional-sobre-intersexualidades-no-porto\/","title":{"rendered":"Congresso internacional sobre Intersexualidades no Porto"},"content":{"rendered":"<p><em>Intersexualidades \u2013 Cruzando Corpos, Cruzando Fronteiras<\/em> \u00e9 o t\u00edtulo do congresso transnacional que se realiza entre 23 e 25 de Mar\u00e7o, no Porto. A iniciativa \u00e9 do grupo Intersexualidades do projeto <em>Literatura e Fronteiras do Conhecimento: Pol\u00edticas de\u00a0Inclus\u00e3o<\/em>, do Instituto de Literatura Comparada Margarida Losa, da Faculdade de Letras da Universidade do Porto.<\/p>\n<p>H\u00e9l\u00e8ne Cixous, Isabel Allegro de Magalh\u00e3es e Jo\u00e3o Ramalho-Santos ser\u00e3o os keynote speakers do encontro, que decorre na Faculdade de Letras da Universidade do Porto e na Funda\u00e7\u00e3o Serralves. O congresso visa promover a \u201cdiscuss\u00e3o em torno das pol\u00edticas de\u00a0inclus\u00e3o e da ideia de comunidades (sociais, liter\u00e1rias e cient\u00edficas) no s\u00e9culo XXI\u201d, \u201cpartindo dos Estudos Feministas, Estudos de G\u00e9nero e Teoria Queer, em articula\u00e7\u00e3o com \u00e1reas\u00a0de saber como a Medicina, a Psicologia, a Hist\u00f3ria, a Filosofia, a Sociologia, a Antropologia, o Direito,\u00a0e a F\u00edsica Te\u00f3rica\u201d.<\/p>\n<p>Mais informa\u00e7\u00f5es <a href=\"https:\/\/sigarra.up.pt\/flup\/pt\/noticias_geral.ver_noticia?p_nr=52522\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intersexualidades \u2013 Cruzando Corpos, Cruzando Fronteiras \u00e9 o t\u00edtulo do congresso transnacional que se realiza entre 23 e 25 de Mar\u00e7o, no Porto. A iniciativa \u00e9 do grupo Intersexualidades do projeto Literatura e Fronteiras do Conhecimento: Pol\u00edticas de\u00a0Inclus\u00e3o, do Instituto de Literatura Comparada Margarida Losa, da Faculdade de Letras da Universidade do Porto. H\u00e9l\u00e8ne Cixous, [&hellip;]<\/p>\n","protected":false},"author":500,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61,60],"tags":[115,313,317,312,314,315,316],"class_list":["post-6967","post","type-post","status-publish","format-standard","hentry","category-eventos-cientificos-internacionais","category-eventos-cientificos-nacionais","tag-congresso","tag-helene-cixou","tag-instituto-de-literatura-comparada-margarida-losa","tag-intersexualidade","tag-isabel-allegro-de-magalhaes","tag-joao-ramalho-santos","tag-literatura-e-fronteiras-do-conhecimento-politicas-de-inclusao"],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts\/6967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/users\/500"}],"replies":[{"embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/comments?post=6967"}],"version-history":[{"count":3,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts\/6967\/revisions"}],"predecessor-version":[{"id":6971,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/posts\/6967\/revisions\/6971"}],"wp:attachment":[{"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/media?parent=6967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/categories?post=6967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spsc.pt\/index.php\/wp-json\/wp\/v2\/tags?post=6967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}